{"id":59,"count":1,"description":"","link":"https:\/\/themes.elmastudio.de\/uku-apia\/tag\/vietnam\/","name":"Vietnam","slug":"vietnam","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/themes.elmastudio.de\/uku-apia\/wp-json\/wp\/v2\/tags\/59","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themes.elmastudio.de\/uku-apia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/themes.elmastudio.de\/uku-apia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/themes.elmastudio.de\/uku-apia\/wp-json\/wp\/v2\/posts?tags=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}